{"id":106054,"date":"2016-11-09T03:44:53","date_gmt":"2016-11-09T10:44:53","guid":{"rendered":"http:\/\/twitter-796302536407793665-post"},"modified":"2016-11-09T03:44:53","modified_gmt":"2016-11-09T10:44:53","slug":"rt-friendlyassh0le-his-own-kid-just-rolled-his","status":"publish","type":"post","link":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/","title":{"rendered":"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;"},"content":{"rendered":"<p>RT <a href=\"http:\/\/twitter.com\/FriendlyAssh0le\">@FriendlyAssh0le<\/a>: &#8220;His own kid just rolled his eyes at him.&#8221; ? https:\/\/t.co\/lOmzVDUU9B<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"http:\/\/blog.twilightfairy.in\/tweets\/wp-content\/uploads\/2016\/11\/fJqwC3ha6TtCLBBn-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"fJqwC3ha6TtCLBBn\" \/><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>RT @FriendlyAssh0le: &#8220;His own kid just rolled his eyes at him.&#8221; ? https:\/\/t.co\/lOmzVDUU9B<\/p>\n","protected":false},"author":2,"featured_media":106053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"status","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-106054","post","type-post","status-publish","format-status","has-post-thumbnail","category-twitter","post_format-post-format-status","czr-hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"RT @FriendlyAssh0le: &quot;His own kid just rolled his eyes at him.&quot; ? https:\/\/t.co\/lOmzVDUU9B\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"twilight\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Twilight Fairy&#039;s tweets | Twilight Fairy&#039;s twitterverse\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy&#039;s tweets\" \/>\n\t\t<meta property=\"og:description\" content=\"RT @FriendlyAssh0le: &quot;His own kid just rolled his eyes at him.&quot; ? https:\/\/t.co\/lOmzVDUU9B\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-11-09T10:44:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-11-09T10:44:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy&#039;s tweets\" \/>\n\t\t<meta name=\"twitter:description\" content=\"RT @FriendlyAssh0le: &quot;His own kid just rolled his eyes at him.&quot; ? https:\/\/t.co\/lOmzVDUU9B\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#article\",\"name\":\"RT @FriendlyAssh0le: \\u201cHis own kid just rolled his\\u2026 | Twilight Fairy's tweets\",\"headline\":\"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;\",\"author\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/author\\\/twilight\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/fJqwC3ha6TtCLBBn.jpg\",\"width\":600,\"height\":1066},\"datePublished\":\"2016-11-09T03:44:53-07:00\",\"dateModified\":\"2016-11-09T03:44:53-07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#webpage\"},\"articleSection\":\"Twitter, Status\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/category\\\/twitter\\\/#listItem\",\"name\":\"Twitter\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/category\\\/twitter\\\/#listItem\",\"position\":2,\"name\":\"Twitter\",\"item\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/category\\\/twitter\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#listItem\",\"name\":\"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#listItem\",\"position\":3,\"name\":\"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/category\\\/twitter\\\/#listItem\",\"name\":\"Twitter\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/#organization\",\"name\":\"Twilight Fairy's tweets\",\"description\":\"Twilight Fairy's twitterverse\",\"url\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/author\\\/twilight\\\/#author\",\"url\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/author\\\/twilight\\\/\",\"name\":\"twilight\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/731b03c222b0391be93fc68d6952357f7245dbf62232c2de2082f4aefbe33ff3?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"twilight\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#webpage\",\"url\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/\",\"name\":\"RT @FriendlyAssh0le: \\u201cHis own kid just rolled his\\u2026 | Twilight Fairy's tweets\",\"description\":\"RT @FriendlyAssh0le: \\\"His own kid just rolled his eyes at him.\\\" ? https:\\\/\\\/t.co\\\/lOmzVDUU9B\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/author\\\/twilight\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/author\\\/twilight\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/fJqwC3ha6TtCLBBn.jpg\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#mainImage\",\"width\":600,\"height\":1066},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/2016\\\/11\\\/09\\\/rt-friendlyassh0le-his-own-kid-just-rolled-his\\\/#mainImage\"},\"datePublished\":\"2016-11-09T03:44:53-07:00\",\"dateModified\":\"2016-11-09T03:44:53-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/#website\",\"url\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/\",\"name\":\"Twilight Fairy's tweets\",\"description\":\"Twilight Fairy's twitterverse\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"http:\\\/\\\/blog.twilightfairy.in\\\/tweets\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy's tweets","description":"RT @FriendlyAssh0le: \"His own kid just rolled his eyes at him.\" ? https:\/\/t.co\/lOmzVDUU9B","canonical_url":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#article","name":"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy's tweets","headline":"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;","author":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/author\/twilight\/#author"},"publisher":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/blog.twilightfairy.in\/tweets\/wp-content\/uploads\/2016\/11\/fJqwC3ha6TtCLBBn.jpg","width":600,"height":1066},"datePublished":"2016-11-09T03:44:53-07:00","dateModified":"2016-11-09T03:44:53-07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#webpage"},"isPartOf":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#webpage"},"articleSection":"Twitter, Status"},{"@type":"BreadcrumbList","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets#listItem","position":1,"name":"Home","item":"http:\/\/blog.twilightfairy.in\/tweets","nextItem":{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets\/category\/twitter\/#listItem","name":"Twitter"}},{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets\/category\/twitter\/#listItem","position":2,"name":"Twitter","item":"http:\/\/blog.twilightfairy.in\/tweets\/category\/twitter\/","nextItem":{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#listItem","name":"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;"},"previousItem":{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#listItem","position":3,"name":"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;","previousItem":{"@type":"ListItem","@id":"http:\/\/blog.twilightfairy.in\/tweets\/category\/twitter\/#listItem","name":"Twitter"}}]},{"@type":"Organization","@id":"http:\/\/blog.twilightfairy.in\/tweets\/#organization","name":"Twilight Fairy's tweets","description":"Twilight Fairy's twitterverse","url":"http:\/\/blog.twilightfairy.in\/tweets\/"},{"@type":"Person","@id":"http:\/\/blog.twilightfairy.in\/tweets\/author\/twilight\/#author","url":"http:\/\/blog.twilightfairy.in\/tweets\/author\/twilight\/","name":"twilight","image":{"@type":"ImageObject","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/731b03c222b0391be93fc68d6952357f7245dbf62232c2de2082f4aefbe33ff3?s=96&d=mm&r=g","width":96,"height":96,"caption":"twilight"}},{"@type":"WebPage","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#webpage","url":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/","name":"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy's tweets","description":"RT @FriendlyAssh0le: \"His own kid just rolled his eyes at him.\" ? https:\/\/t.co\/lOmzVDUU9B","inLanguage":"en-US","isPartOf":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/#website"},"breadcrumb":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#breadcrumblist"},"author":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/author\/twilight\/#author"},"creator":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/author\/twilight\/#author"},"image":{"@type":"ImageObject","url":"http:\/\/blog.twilightfairy.in\/tweets\/wp-content\/uploads\/2016\/11\/fJqwC3ha6TtCLBBn.jpg","@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#mainImage","width":600,"height":1066},"primaryImageOfPage":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/#mainImage"},"datePublished":"2016-11-09T03:44:53-07:00","dateModified":"2016-11-09T03:44:53-07:00"},{"@type":"WebSite","@id":"http:\/\/blog.twilightfairy.in\/tweets\/#website","url":"http:\/\/blog.twilightfairy.in\/tweets\/","name":"Twilight Fairy's tweets","description":"Twilight Fairy's twitterverse","inLanguage":"en-US","publisher":{"@id":"http:\/\/blog.twilightfairy.in\/tweets\/#organization"}}]},"og:locale":"en_US","og:site_name":"Twilight Fairy's tweets | Twilight Fairy's twitterverse","og:type":"article","og:title":"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy's tweets","og:description":"RT @FriendlyAssh0le: &quot;His own kid just rolled his eyes at him.&quot; ? https:\/\/t.co\/lOmzVDUU9B","og:url":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/","article:published_time":"2016-11-09T10:44:53+00:00","article:modified_time":"2016-11-09T10:44:53+00:00","twitter:card":"summary","twitter:title":"RT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026 | Twilight Fairy's tweets","twitter:description":"RT @FriendlyAssh0le: &quot;His own kid just rolled his eyes at him.&quot; ? https:\/\/t.co\/lOmzVDUU9B"},"aioseo_meta_data":{"post_id":"106054","title":null,"description":null,"keywords":null,"keyphrases":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-08 12:52:50","updated":"2025-06-08 18:14:33","primary_term":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/blog.twilightfairy.in\/tweets\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/blog.twilightfairy.in\/tweets\/category\/twitter\/\" title=\"Twitter\">Twitter<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRT @FriendlyAssh0le: \u201cHis own kid just rolled his\u2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/blog.twilightfairy.in\/tweets"},{"label":"Twitter","link":"http:\/\/blog.twilightfairy.in\/tweets\/category\/twitter\/"},{"label":"RT @FriendlyAssh0le: &#8220;His own kid just rolled his&#8230;","link":"http:\/\/blog.twilightfairy.in\/tweets\/2016\/11\/09\/rt-friendlyassh0le-his-own-kid-just-rolled-his\/"}],"_links":{"self":[{"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/posts\/106054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/comments?post=106054"}],"version-history":[{"count":0,"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/posts\/106054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/media\/106053"}],"wp:attachment":[{"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/media?parent=106054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/categories?post=106054"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.twilightfairy.in\/tweets\/wp-json\/wp\/v2\/tags?post=106054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}